{"id":4751,"date":"2023-10-10T13:30:57","date_gmt":"2023-10-10T11:30:57","guid":{"rendered":"https:\/\/fes-heidenheim.de\/gymnasium\/?p=4751"},"modified":"2023-10-10T13:31:42","modified_gmt":"2023-10-10T11:31:42","slug":"mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen","status":"publish","type":"post","link":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/","title":{"rendered":"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen"},"content":{"rendered":"\n<p><strong>Neue Schule, neue Lehrkr\u00e4fte, neue Klassenkam\u00ader\u00adaden\u2026 f\u00fcr die \u00fcber 40 neuen F\u00fcn\u00adftk\u00adl\u00e4ssler des FES-Gym\u00adna\u00adsi\u00adums und der FES-Realschule standen drei Ken\u00adnen\u00adlern\u00adtage auf dem Pro\u00adgramm, um nicht nur die neuen Klassenkam\u00ader\u00adaden, son\u00addern auch das Schul\u00adhaus, die Klassen\u00adlehrer und das Schul\u00adgel\u00e4nde aus\u00adgiebig ken\u00adnen\u00adzuler\u00adnen und zu erkunden.<\/strong><\/p>\n\n\n\n<p>F\u00fcr den ersten Tag war ein Aus\u00adflug auf einen nahegele\u00adge\u00adnen Bauern\u00adhof mit Schafzucht geplant. Mit dem Zug ging es gemein\u00adsam nach Giengen\/Brenz, dann zu Fu\u00df bei sch\u00f6n\u00adstem Wet\u00adter zum Hof, wo uns die B\u00e4uerin mit ihrer Tochter bere\u00adits erwartete. Die bei\u00adden 5. Klassen wur\u00adden aufgeteilt, sodass je eine Gruppe kleine Schafe aus Knet\u00admasse und Wolle filzte, die andere eine aus\u00adgiebige Hof\u00adf\u00fchrung mit vie\u00adlen inter\u00ades\u00adsan\u00adten Erk\u00adl\u00e4run\u00adgen, beispiel\u00adsweise zum Schlachthaus und zur Bet\u00e4ubung, erhielt. Viele h\u00fcb\u00adsche Kunst\u00adwerke ent\u00adstanden, die die Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler anschlie\u00dfend mit nach Hause nehmen durften und so ein Andenken an diesen Tag in toller Gemein\u00adschaft hatten.<\/p>\n\n\n\n<p>Am Don\u00adner\u00adstag und Fre\u00aditag stand dann das High\u00adlight f\u00fcr viele Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler auf dem Pro\u00adgramm: eine \u00dcber\u00adnach\u00adtung im Schul\u00adhaus mit gemein\u00adsamem Lager\u00adfeuer, leck\u00aderen W\u00fcrstchen und Stock\u00adbrot. Die St\u00f6cke mussten am Vor\u00admit\u00adtag im nahe gele\u00adge\u00adnen Wald gesam\u00admelt und geschnitzt wer\u00adden, mit\u00adtags durften die Kinder ihre freie Zeit beim Fu\u00dfball- und Tis\u00adchten\u00adnis\u00adspie\u00adlen, Fre\u00adund\u00adschafts\u00adb\u00e4n\u00adderkn\u00fcpfen und am gro\u00dfz\u00fcgi\u00adgen Kuchen\u00adbuf\u00adfet genie\u00dfen (an dieser Stelle noch ein\u00admal ein gro\u00dfen Dankesch\u00f6n an die Eltern \ud83d\ude09 ) Gegen Abend wur\u00adden gemein\u00adsam einige Spiele zum noch besseren Ken\u00adnen\u00adler\u00adnen gespielt, an welche sich eine kurze Andacht zum The\u00adma Fre\u00adund\u00adschaft und N\u00e4ch\u00adsten\u00adliebe anschloss und mit eini\u00adgen Liedern abgerun\u00addet&nbsp;wurde.<\/p>\n\n\n\n<p>Auf die Nacht hat\u00adten sich viele bere\u00adits seit Tagen am meis\u00adten gefreut, stand doch Ver\u00adsteck\u00adspie\u00adlen im Dunkeln auf dem gesamten Schul\u00adgel\u00e4nde und Schul\u00adhaus auf dem Pro\u00adgramm \u2013 ein Ken\u00adnen\u00adler\u00adnen des Geb\u00e4udes also auf eine ganz andere Art und&nbsp;Weise.<\/p>\n\n\n\n<p>Trotz der f\u00fcr viele recht kurzen Nacht starteten wir am n\u00e4ch\u00adsten Mor\u00adgen motiviert mit unserem gemein\u00adsamen Fr\u00fch\u00adst\u00fcck, sodass die Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler gut gest\u00e4rkt ihre Zim\u00admer und das Schul\u00adhaus aufr\u00e4u\u00admen kon\u00adnten, bevor sie ins wohlver\u00addi\u00adente Woch\u00adenende ent\u00adlassen wurden\u2026<\/p>\n\n\n\n<p>Ins\u00adge\u00adsamt erlebten die F\u00fcn\u00adftk\u00adl\u00e4ssler eine gute und geseg\u00adnete Zeit, in der viele neue Fre\u00adund\u00adschaften gekn\u00fcpft und die FES mit allem, was sie zu bieten hat, ken\u00adnen\u00adgel\u00adernt wer\u00adden konnte.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped\"><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"1024\" data-id=\"4766\" src=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-02-2-717x1024.jpeg\" alt class=\"wp-image-4766\" srcset=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-02-2-717x1024.jpeg 717w, https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-02-2-480x685.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 717px, 100vw\"><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-04-461x1024.jpeg\" alt=\"Dieses Bild hat ein leeres Alt-Attribut. Der Dateiname ist Weiteres-Bild-04-461x1024.jpeg\"><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"574\" height=\"1024\" data-id=\"4770\" src=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-03-2-574x1024.jpeg\" alt class=\"wp-image-4770\" srcset=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-03-2-574x1024.jpeg 574w, https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-03-2-480x856.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 574px, 100vw\"><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"586\" src=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-07-2-1024x586.jpg\" alt class=\"wp-image-4768\" srcset=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-07-2-980x560.jpg 980w, https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-07-2-480x275.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\"><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"506\" src=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-05-2-1024x506.jpeg\" alt class=\"wp-image-4769\" srcset=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-05-2-980x484.jpeg 980w, https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-05-2-480x237.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\"><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"1024\" src=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-01-1-591x1024.jpeg\" alt class=\"wp-image-4762\" srcset=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-01-1-591x1024.jpeg 591w, https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Weiteres-Bild-01-1-480x831.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 591px, 100vw\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Neue Schule, neue Lehrkr\u00e4fte, neue Klassenkam\u00ader\u00adaden\u2026 f\u00fcr die \u00fcber 40 neuen F\u00fcn\u00adftk\u00adl\u00e4ssler des FES-Gym\u00ad\u00adna\u00adsi\u00adums und der FES-Realschule standen drei Ken\u00adnen\u00adlern\u00adtage auf dem Pro\u00adgramm, um nicht nur die neuen Klassenkam\u00ader\u00adaden, sondern&nbsp;[\u2026]<\/p>\n","protected":false},"author":12,"featured_media":4752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[1,30,29],"tags":[],"class_list":["post-4751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fes-gymnasium","category-fes-realschule"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\" \/>\n<meta property=\"og:description\" content=\"Neue Schule, neue Lehrkr\u00e4fte, neue Klassenkam\u00ader\u00adaden\u2026 f\u00fcr die \u00fcber 40 neuen F\u00fcn\u00adftk\u00adl\u00e4ssler des FES-Gym\u00adna\u00adsi\u00adums und der FES-Realschule standen drei Ken\u00adnen\u00adlern\u00adtage auf dem Pro\u00adgramm, um nicht nur die neuen Klassenkam\u00ader\u00adaden, son\u00addern [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/\" \/>\n<meta property=\"og:site_name\" content=\"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T11:30:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T11:31:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen\",\"datePublished\":\"2023-10-10T11:30:57+00:00\",\"dateModified\":\"2023-10-10T11:31:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/\"},\"wordCount\":394,\"image\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg\",\"articleSection\":{\"1\":\"FES Gymnasium\",\"2\":\"FES Realschule\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/\",\"name\":\"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg\",\"datePublished\":\"2023-10-10T11:30:57+00:00\",\"dateModified\":\"2023-10-10T11:31:42+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg\",\"contentUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg\",\"width\":1600,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#website\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/\",\"name\":\"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\",\"description\":\"Eine weitere Freie Evangelische Schule Heidenheim e.V. Websites Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/","og_locale":"de_DE","og_type":"article","og_title":"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","og_description":"Neue Schule, neue Lehrkr\u00e4fte, neue Klassenkam\u00ader\u00adaden\u2026 f\u00fcr die \u00fcber 40 neuen F\u00fcn\u00adftk\u00adl\u00e4ssler des FES-Gym\u00adna\u00adsi\u00adums und der FES-Realschule standen drei Ken\u00adnen\u00adlern\u00adtage auf dem Pro\u00adgramm, um nicht nur die neuen Klassenkam\u00ader\u00adaden, son\u00addern [&hellip;]","og_url":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/","og_site_name":"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","article_published_time":"2023-10-10T11:30:57+00:00","article_modified_time":"2023-10-10T11:31:42+00:00","og_image":[{"width":1600,"height":721,"url":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/#article","isPartOf":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/"},"author":{"name":"","@id":""},"headline":"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen","datePublished":"2023-10-10T11:30:57+00:00","dateModified":"2023-10-10T11:31:42+00:00","mainEntityOfPage":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/"},"wordCount":394,"image":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/#primaryimage"},"thumbnailUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg","articleSection":{"1":"FES Gymnasium","2":"FES Realschule"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/","url":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/","name":"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","isPartOf":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/#primaryimage"},"image":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/#primaryimage"},"thumbnailUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg","datePublished":"2023-10-10T11:30:57+00:00","dateModified":"2023-10-10T11:31:42+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/#primaryimage","url":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg","contentUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-Kennenlerntage-Kl.5.jpeg","width":1600,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/mit-abstand-die-beste-einschulung-wir-begruessen-die-neuen-5-klassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fes-heidenheim.de\/gymnasium\/"},{"@type":"ListItem","position":2,"name":"Mit Abstand die beste Einschulung: Wir begr\u00fc\u00dfen die neuen 5. Klassen"}]},{"@type":"WebSite","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#website","url":"https:\/\/fes-heidenheim.de\/gymnasium\/","name":"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","description":"Eine weitere Freie Evangelische Schule Heidenheim e.V. Websites Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fes-heidenheim.de\/gymnasium\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"","url":"https:\/\/fes-heidenheim.de\/gymnasium\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/4751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/comments?post=4751"}],"version-history":[{"count":1,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/4751\/revisions"}],"predecessor-version":[{"id":4771,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/4751\/revisions\/4771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/media\/4752"}],"wp:attachment":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/media?parent=4751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/categories?post=4751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/tags?post=4751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}