{"id":4772,"date":"2023-10-10T13:39:48","date_gmt":"2023-10-10T11:39:48","guid":{"rendered":"https:\/\/fes-heidenheim.de\/gymnasium\/?p=4772"},"modified":"2023-10-10T13:39:51","modified_gmt":"2023-10-10T11:39:51","slug":"ag-angebote-1-schulhalbjahr-2023-24","status":"publish","type":"post","link":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/","title":{"rendered":"AG-Angebote \u2013 1. Schulhalbjahr 2023\/24"},"content":{"rendered":"\n<p><strong>Forschen, Tanzen, Latein\u00adler\u00adnen, Musizieren, Fu\u00dfball\u00adspie\u00adlen mit dem FCH, Pock\u00adet\u00adbike fahren, B\u00fccher\u00adclub\u2026 Zum Schul\u00adjahresstart 2023\/24 gibt es f\u00fcr die Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler an FES-Gym\u00adna\u00adsi\u00adum und FES-Realschule wieder vielf\u00e4ltige AG-Angebote<\/strong><\/p>\n\n\n\n<p><em>\u201eDie Schule ist, das wei\u00df man ja, in erster Lin\u00adie dazu da, den Guten wie den B\u00f6sewichtern den Lehrstoff qua\u00adsi einzutrichtern\u2026\u201c<\/em><\/p>\n\n\n\n<p><br>Heinz Erhardts Blick auf Schule l\u00e4dt bes\u00adtimmt viele zum Schmun\u00adzeln ein, ist aber zum Gl\u00fcck schon lange nur mehr ein Gedicht und vor allem Geschichte. In Bezug auf \u201eSchule-heute\u201c d\u00fcrfte man da get\u00adrost unrein weit\u00ader dicht\u00aden \u201ein erster Lin\u00adie daf\u00fcr da, ein jedes Kind in seinem Wesen voranzubrin\u00adgen und zu sch\u00e4tzen\u201c. <br>An unser\u00ader Freien Evan\u00adge\u00adlis\u00adchen Schule hat dieses Denken lange Tra\u00addi\u00adtion und so gibt es auch dieses Jahr wieder an FES-Gym\u00adna\u00adsi\u00adum und FES-Realschule w\u00f6chentlich viele unter\u00adschiedliche AG-Ange\u00adbote f\u00fcr die Klassen\u00adstufen 5 \u2013 7.<br>Ob die indi\u00advidu\u00adellen Vor\u00adlieben eher sportlich, aben\u00adteuer\u00adlustig, gem\u00fctlich oder wiss\u00adbe\u00adgierig sind: Beim Lesen, Fu\u00dfball\u00adspie\u00adlen, Forschen, Latein\u00adler\u00adnen, Rock\u00aden, Pock\u00adet\u00adbiken, Tanzen oder der M\u00e4d\u00adchen-AG kom\u00admen alle Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler der Unter\u00adstufen auf ihre Kosten. Warum es auch nicht ver\u00adwun\u00addert, dass diese noten\u00adfreie Unter\u00adricht\u00adszeit in der Schul\u00adwoche bei den jun\u00adgen Realsch\u00fclern und Gym\u00adnasi\u00adas\u00adten beson\u00adders beliebt ist. Ein\u00admal raus aus der Klasse und unter \u201eSeines\u00adgle\u00adichen\u201c sein, hil\u00adft auch neue Kraft zu tanken und so manch\u00ades Her\u00adaus\u00adfordernde in der Schule gelassen\u00ader zu sehen.<br>Und wenn man sich doch mal ver\u00adw\u00e4hlt hat? Der Spa\u00df kommt sich\u00ader in kein\u00ader der AGs zu kurz und zum 2.Schulhalbjahr k\u00f6n\u00adnen wieder neue AG-Ange\u00adbote gew\u00e4hlt werden\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Forschen, Tanzen, Latein\u00adler\u00adnen, Musizieren, Fu\u00dfball\u00adspie\u00adlen mit dem FCH, Pock\u00adet\u00adbike fahren, B\u00fccher\u00adclub\u2026 Zum Schul\u00adjahresstart 2023\/24 gibt es f\u00fcr die Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler an FES-Gym\u00ad\u00adna\u00adsi\u00adum und FES-Realschule wieder vielf\u00e4ltige AG-Ange\u00adbote \u201eDie Schule&nbsp;[\u2026]<\/p>\n","protected":false},"author":12,"featured_media":4773,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[1,30,29],"tags":[],"class_list":["post-4772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fes-gymnasium","category-fes-realschule"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AG-Angebote \u2013 1. Schulhalbjahr 2023\/24 - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AG-Angebote \u2013 1. Schulhalbjahr 2023\/24 - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\" \/>\n<meta property=\"og:description\" content=\"Forschen, Tanzen, Latein\u00adler\u00adnen, Musizieren, Fu\u00dfball\u00adspie\u00adlen mit dem FCH, Pock\u00adet\u00adbike fahren, B\u00fccher\u00adclub\u2026 Zum Schul\u00adjahresstart 2023\/24 gibt es f\u00fcr die Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler an FES-Gym\u00adna\u00adsi\u00adum und FES-Realschule wieder vielf\u00e4ltige AG-Angebote \u201eDie Schule [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T11:39:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T11:39:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AG-Angebote \u2013 1. Schulhalbjahr 2023\\\/24\",\"datePublished\":\"2023-10-10T11:39:48+00:00\",\"dateModified\":\"2023-10-10T11:39:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/\"},\"wordCount\":258,\"image\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg\",\"articleSection\":{\"1\":\"FES Gymnasium\",\"2\":\"FES Realschule\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/\",\"name\":\"AG-Angebote \u2013 1. Schulhalbjahr 2023\\\/24 - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg\",\"datePublished\":\"2023-10-10T11:39:48+00:00\",\"dateModified\":\"2023-10-10T11:39:51+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/10\\\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2023\\\/10\\\/10\\\/ag-angebote-1-schulhalbjahr-2023-24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AG-Angebote \u2013 1. Schulhalbjahr 2023\\\/24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#website\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/\",\"name\":\"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\",\"description\":\"Eine weitere Freie Evangelische Schule Heidenheim e.V. Websites Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AG-Angebote \u2013 1. Schulhalbjahr 2023\/24 - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/","og_locale":"de_DE","og_type":"article","og_title":"AG-Angebote \u2013 1. Schulhalbjahr 2023\/24 - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","og_description":"Forschen, Tanzen, Latein\u00adler\u00adnen, Musizieren, Fu\u00dfball\u00adspie\u00adlen mit dem FCH, Pock\u00adet\u00adbike fahren, B\u00fccher\u00adclub\u2026 Zum Schul\u00adjahresstart 2023\/24 gibt es f\u00fcr die Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler an FES-Gym\u00adna\u00adsi\u00adum und FES-Realschule wieder vielf\u00e4ltige AG-Angebote \u201eDie Schule [&hellip;]","og_url":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/","og_site_name":"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","article_published_time":"2023-10-10T11:39:48+00:00","article_modified_time":"2023-10-10T11:39:51+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/#article","isPartOf":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/"},"author":{"name":"","@id":""},"headline":"AG-Angebote \u2013 1. Schulhalbjahr 2023\/24","datePublished":"2023-10-10T11:39:48+00:00","dateModified":"2023-10-10T11:39:51+00:00","mainEntityOfPage":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/"},"wordCount":258,"image":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/#primaryimage"},"thumbnailUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg","articleSection":{"1":"FES Gymnasium","2":"FES Realschule"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/","url":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/","name":"AG-Angebote \u2013 1. Schulhalbjahr 2023\/24 - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","isPartOf":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/#primaryimage"},"image":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/#primaryimage"},"thumbnailUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg","datePublished":"2023-10-10T11:39:48+00:00","dateModified":"2023-10-10T11:39:51+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/#primaryimage","url":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg","contentUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2023\/10\/Beitragsbild-zum-BLOG-Beitrag-AG-Angebote-1.Schulhalbjahr-2023-24-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2023\/10\/10\/ag-angebote-1-schulhalbjahr-2023-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fes-heidenheim.de\/gymnasium\/"},{"@type":"ListItem","position":2,"name":"AG-Angebote \u2013 1. Schulhalbjahr 2023\/24"}]},{"@type":"WebSite","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#website","url":"https:\/\/fes-heidenheim.de\/gymnasium\/","name":"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","description":"Eine weitere Freie Evangelische Schule Heidenheim e.V. Websites Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fes-heidenheim.de\/gymnasium\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"","url":"https:\/\/fes-heidenheim.de\/gymnasium\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/4772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/comments?post=4772"}],"version-history":[{"count":1,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/4772\/revisions"}],"predecessor-version":[{"id":4774,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/4772\/revisions\/4774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/media?parent=4772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/categories?post=4772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/tags?post=4772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}