{"id":5951,"date":"2025-01-20T10:11:01","date_gmt":"2025-01-20T09:11:01","guid":{"rendered":"https:\/\/fes-heidenheim.de\/gymnasium\/?p=5951"},"modified":"2026-06-09T18:48:07","modified_gmt":"2026-06-09T16:48:07","slug":"nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1","status":"publish","type":"post","link":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/","title":{"rendered":"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1!"},"content":{"rendered":"\n<p>K\u00fcr\u00adzlich beka\u00admen 10 Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler unseres FES-Gym\u00adna\u00adsi\u00adums ihre DELF-Zer\u00adti\u00adfikate von zwei Fach\u00adlehrkr\u00e4ften der Fach\u00adschaft Franz\u00f6\u00adsisch, Frau Dr. Albrecht und Frau Kas\u00addorff, gemein\u00adsam mit Schulleit\u00ader Andreas Borkeloh verliehen.<\/p>\n\n\n\n<p>Bere\u00adits im ver\u00adgan\u00adgenen Schul\u00adjahr wur\u00adden in ein\u00ader zen\u00adtral gestell\u00adten Klasse\u00adnar\u00adbeit in Franz\u00f6\u00adsisch in Klasse 10 die Kom\u00adpe\u00adtenzbere\u00adiche H\u00f6rver\u00adste\u00adhen, Lesev\u00ader\u00adste\u00adhen und Schreiben gepr\u00fcft.<\/p>\n\n\n\n<p>Die Franz\u00f6\u00adsis\u00adchkol\u00adlegin\u00adnen Frau Dr. Albrecht und Frau Kas\u00addorff, welche durch eine aufw\u00e4ndi\u00adge Schu\u00adlung die Zulas\u00adsung als offizielle DELF-Pr\u00fcferin\u00adnen erwor\u00adben haben, nah\u00admen die m\u00fcndlichen Pr\u00fc\u00adfun\u00adgen ab. In den m\u00fcndlichen Pr\u00fc\u00adfun\u00adgen stell\u00adten die Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler ihre Sprachkom\u00adpe\u00adtenz unter Beweis und kon\u00adnten so nun final jew\u00adeils ihr DELF-Diplom erwerben.<\/p>\n\n\n\n<p>Damit sind sie im Besitz eines inter\u00adna\u00adtion\u00adal anerkan\u00adnten Diploms, das nach\u00adweist, dass sie die franz\u00f6\u00adsis\u00adche Sprache nach dem Gemein\u00adsamen Europ\u00e4is\u00adchen Ref\u00aderen\u00adzrah\u00admen auf Niveau B1 (fort\u00adgeschrit\u00adtene Sprachver\u00adwen\u00addung) beherrschen.<\/p>\n\n\n\n<p>Die FES-Schul\u00adge\u00admein\u00adschaft grat\u00aduliert her\u00adzlich zum bestande\u00adnen Zer\u00adti\u00adfikat: Bene\u00addict Bopp, Elias Bunk, Franziska Elsen\u00adhans, Daniela Graf, Dominik G\u00f6ggel\u00admann, Madi\u00adta Jahnke, Mar\u00adi\u00adan Maier, Lili\u00adta Neimane, Sarah Schulz-Kalil und Kathrin Wei\u00dfenberger.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcr\u00adzlich beka\u00admen 10 Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler unseres FES-Gym\u00ad\u00adna\u00adsi\u00adums ihre DELF-Zer\u00adti\u00ad\u00adfikate von zwei Fach\u00adlehrkr\u00e4ften der Fach\u00adschaft Franz\u00f6\u00adsisch, Frau Dr. Albrecht und Frau Kas\u00addorff, gemein\u00adsam mit Schulleit\u00ader Andreas Borkeloh ver\u00adliehen. Bere\u00adits&nbsp;im&nbsp;[\u2026]<\/p>\n","protected":false},"author":15,"featured_media":5952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-5951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fes-gymnasium"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1! - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1! - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\" \/>\n<meta property=\"og:description\" content=\"K\u00fcr\u00adzlich beka\u00admen 10 Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler unseres FES-Gym\u00adna\u00adsi\u00adums ihre DELF-Zer\u00adti\u00adfikate von zwei Fach\u00adlehrkr\u00e4ften der Fach\u00adschaft Franz\u00f6\u00adsisch, Frau Dr. Albrecht und Frau Kas\u00addorff, gemein\u00adsam mit Schulleit\u00ader Andreas Borkeloh verliehen. Bere\u00adits im [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/\" \/>\n<meta property=\"og:site_name\" content=\"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-20T09:11:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T16:48:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2025\/01\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sekretariatgym\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"sekretariatgym\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/\"},\"author\":{\"name\":\"sekretariatgym\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#\\\/schema\\\/person\\\/e614df80cf0124a0861921322ba81ee9\"},\"headline\":\"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1!\",\"datePublished\":\"2025-01-20T09:11:01+00:00\",\"dateModified\":\"2026-06-09T16:48:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/\"},\"wordCount\":180,\"image\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/01\\\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg\",\"articleSection\":[\"FES Gymnasium\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/\",\"name\":\"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1! - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/01\\\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg\",\"datePublished\":\"2025-01-20T09:11:01+00:00\",\"dateModified\":\"2026-06-09T16:48:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#\\\/schema\\\/person\\\/e614df80cf0124a0861921322ba81ee9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/01\\\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/01\\\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"K\u00fcrzlich bekamen 10 Sch\u00fclerinnen und Sch\u00fcler unseres FES-Gymnasiums ihre DELF-Zertifikate von zwei Fachlehrkr\u00e4ften der Fachschaft Franz\u00f6sisch, Frau Dr. Albrecht und Frau Kasdorff, gemeinsam mit Schulleiter Andreas Borkeloh verliehen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/2025\\\/01\\\/20\\\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#website\",\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/\",\"name\":\"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.\",\"description\":\"Eine weitere Freie Evangelische Schule Heidenheim e.V. Websites Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/#\\\/schema\\\/person\\\/e614df80cf0124a0861921322ba81ee9\",\"name\":\"sekretariatgym\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8196f14ce1450e8b1558ed9138138a8a40a91d9ddc1e02556e5dd141376b7e3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8196f14ce1450e8b1558ed9138138a8a40a91d9ddc1e02556e5dd141376b7e3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8196f14ce1450e8b1558ed9138138a8a40a91d9ddc1e02556e5dd141376b7e3a?s=96&d=mm&r=g\",\"caption\":\"sekretariatgym\"},\"url\":\"https:\\\/\\\/fes-heidenheim.de\\\/gymnasium\\\/author\\\/sekretariatgym\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1! - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1! - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","og_description":"K\u00fcr\u00adzlich beka\u00admen 10 Sch\u00fc\u00adlerin\u00adnen und Sch\u00fcler unseres FES-Gym\u00adna\u00adsi\u00adums ihre DELF-Zer\u00adti\u00adfikate von zwei Fach\u00adlehrkr\u00e4ften der Fach\u00adschaft Franz\u00f6\u00adsisch, Frau Dr. Albrecht und Frau Kas\u00addorff, gemein\u00adsam mit Schulleit\u00ader Andreas Borkeloh verliehen. Bere\u00adits im [&hellip;]","og_url":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/","og_site_name":"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","article_published_time":"2025-01-20T09:11:01+00:00","article_modified_time":"2026-06-09T16:48:07+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2025\/01\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg","type":"image\/jpeg"}],"author":"sekretariatgym","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"sekretariatgym","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/#article","isPartOf":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/"},"author":{"name":"sekretariatgym","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#\/schema\/person\/e614df80cf0124a0861921322ba81ee9"},"headline":"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1!","datePublished":"2025-01-20T09:11:01+00:00","dateModified":"2026-06-09T16:48:07+00:00","mainEntityOfPage":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/"},"wordCount":180,"image":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/#primaryimage"},"thumbnailUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2025\/01\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg","articleSection":["FES Gymnasium"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/","url":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/","name":"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1! - Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","isPartOf":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/#primaryimage"},"image":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/#primaryimage"},"thumbnailUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2025\/01\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg","datePublished":"2025-01-20T09:11:01+00:00","dateModified":"2026-06-09T16:48:07+00:00","author":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#\/schema\/person\/e614df80cf0124a0861921322ba81ee9"},"breadcrumb":{"@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/#primaryimage","url":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2025\/01\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg","contentUrl":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-content\/uploads\/sites\/8\/2025\/01\/klein-Beitragsbild-zum-BLOG-Beitrag-Delf-Zertifikat-B1-scaled.jpg","width":2560,"height":1707,"caption":"K\u00fcrzlich bekamen 10 Sch\u00fclerinnen und Sch\u00fcler unseres FES-Gymnasiums ihre DELF-Zertifikate von zwei Fachlehrkr\u00e4ften der Fachschaft Franz\u00f6sisch, Frau Dr. Albrecht und Frau Kasdorff, gemeinsam mit Schulleiter Andreas Borkeloh verliehen."},{"@type":"BreadcrumbList","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/2025\/01\/20\/nos-felicitations-wir-gratulieren-zum-bestandenen-zertifikat-delf-b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fes-heidenheim.de\/gymnasium\/"},{"@type":"ListItem","position":2,"name":"\u201eNos f\u00e9licitations!\u201c \u2013 Wir gratulieren zum bestandenen Zertifikat DELF-B1!"}]},{"@type":"WebSite","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#website","url":"https:\/\/fes-heidenheim.de\/gymnasium\/","name":"Gymnasium | Freie Evangelische Schule und Kindertagesst\u00e4tte Heidenheim e. V.","description":"Eine weitere Freie Evangelische Schule Heidenheim e.V. Websites Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fes-heidenheim.de\/gymnasium\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/fes-heidenheim.de\/gymnasium\/#\/schema\/person\/e614df80cf0124a0861921322ba81ee9","name":"sekretariatgym","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8196f14ce1450e8b1558ed9138138a8a40a91d9ddc1e02556e5dd141376b7e3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8196f14ce1450e8b1558ed9138138a8a40a91d9ddc1e02556e5dd141376b7e3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8196f14ce1450e8b1558ed9138138a8a40a91d9ddc1e02556e5dd141376b7e3a?s=96&d=mm&r=g","caption":"sekretariatgym"},"url":"https:\/\/fes-heidenheim.de\/gymnasium\/author\/sekretariatgym\/"}]}},"_links":{"self":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/5951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/comments?post=5951"}],"version-history":[{"count":1,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/5951\/revisions"}],"predecessor-version":[{"id":5953,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/posts\/5951\/revisions\/5953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/media\/5952"}],"wp:attachment":[{"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/media?parent=5951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/categories?post=5951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fes-heidenheim.de\/gymnasium\/wp-json\/wp\/v2\/tags?post=5951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}